{"id":66258,"date":"2026-07-08T14:22:40","date_gmt":"2026-07-08T12:22:40","guid":{"rendered":"https:\/\/www.accuracy.com\/?p=66258"},"modified":"2026-07-08T14:35:49","modified_gmt":"2026-07-08T12:35:49","slug":"retour-sur-la-9e-edition-des-ateliers-sur-le-brevet-organises-par-le-cabinet-davocats-august-debouzy","status":"publish","type":"post","link":"https:\/\/www.accuracy.com\/fr\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/","title":{"rendered":"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"66258\" class=\"elementor elementor-66258\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c84d662 e-flex e-con-boxed e-con e-parent\" data-id=\"c84d662\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf34eda elementor-widget elementor-widget-text-editor\" data-id=\"cf34eda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Notre associ\u00e9 <strong><a href=\"https:\/\/www.accuracy.com\/fr\/equipe\/sebastien-gonnet\/\" target=\"_blank\" rel=\"noopener\">S\u00e9bastien Gonnet<\/a><\/strong>\u00a0a r\u00e9cemment particip\u00e9 \u00e0 la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d'avocats <strong>August Debouzy<\/strong>, qui a rassembl\u00e9 plus de 70 participants.<\/p><p>Cet \u00e9v\u00e9nement annuel a r\u00e9uni des professionnels de la propri\u00e9t\u00e9 intellectuelle afin d\u2019\u00e9changer sur les \u00e9volutions majeures et les d\u00e9fis pratiques du secteur des brevets. Le programme de cette ann\u00e9e portait sur des sujets tels que la comparaison entre l\u2019Office europ\u00e9en des brevets (OEB) et la Juridiction unifi\u00e9e du brevet (JUB), l\u2019articulation entre les brevets et d\u2019autres m\u00e9canismes de protection, ainsi que les r\u00e9centes \u00e9volutions juridiques dans ce domaine.<\/p><p>Lors de cet \u00e9v\u00e9nement, S\u00e9bastien Gonnet a particip\u00e9 aux discussions portant sur les aspects financiers des contrats de licence. Aux c\u00f4t\u00e9s de Pierre-Olivier Ally, il a abord\u00e9 la propri\u00e9t\u00e9 intellectuelle sous un angle d\u00e9passant le cadre du contentieux, en se concentrant sur la structuration, la n\u00e9gociation et la valorisation des accords de licence.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a74a51 elementor-blockquote--skin-quotation elementor-widget elementor-widget-blockquote\" data-id=\"2a74a51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tLes d\u00e9fis li\u00e9s \u00e0 la propri\u00e9t\u00e9 intellectuelle gagnent sans cesse en complexit\u00e9, et seule une combinaison d\u2019expertises \u2013 tant juridiques qu\u2019\u00e9conomiques et financi\u00e8res \u2013 permet d\u2019appr\u00e9hender pleinement tous les aspects de ces questions.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">S\u00e9bastien Gonnet, associ\u00e9 chez Accuracy<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Notre associ\u00e9 S\u00e9bastien Gonnet\u00a0a r\u00e9cemment particip\u00e9 \u00e0 la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy, r\u00e9unissant plus de 70 participants. Cet \u00e9v\u00e9nement annuel a rassembl\u00e9 des professionnels de la propri\u00e9t\u00e9 intellectuelle pour \u00e9changer sur les \u00e9volutions majeures et les d\u00e9fis pratiques du secteur des brevets. Le programme de cette [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,58],"tags":[],"class_list":["post-66258","post","type-post","status-publish","format-standard","hentry","category-france","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy - Accuracy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.accuracy.com\/fr\/retour-sur-la-9e-edition-des-ateliers-sur-le-brevet-organises-par-le-cabinet-davocats-august-debouzy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy\" \/>\n<meta property=\"og:description\" content=\"Notre associ\u00e9 S\u00e9bastien Gonnet\u00a0a r\u00e9cemment particip\u00e9 \u00e0 la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy, r\u00e9unissant plus de 70 participants. Cet \u00e9v\u00e9nement annuel a rassembl\u00e9 des professionnels de la propri\u00e9t\u00e9 intellectuelle pour \u00e9changer sur les \u00e9volutions majeures et les d\u00e9fis pratiques du secteur des brevets. Le programme de cette [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.accuracy.com\/fr\/retour-sur-la-9e-edition-des-ateliers-sur-le-brevet-organises-par-le-cabinet-davocats-august-debouzy\/\" \/>\n<meta property=\"og:site_name\" content=\"Accuracy\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-08T12:22:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:35:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.accuracy.com\/wp-content\/uploads\/2023\/10\/Accuracy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Levy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Etienne Levy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/\"},\"author\":{\"name\":\"Etienne Levy\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#\\\/schema\\\/person\\\/0121122fa331675601ed145cc5dd6182\"},\"headline\":\"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy\",\"datePublished\":\"2026-07-08T12:22:40+00:00\",\"dateModified\":\"2026-07-08T12:35:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/\"},\"wordCount\":232,\"publisher\":{\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#organization\"},\"articleSection\":[\"France\",\"News\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/\",\"url\":\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/\",\"name\":\"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy - Accuracy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#website\"},\"datePublished\":\"2026-07-08T12:22:40+00:00\",\"dateModified\":\"2026-07-08T12:35:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.accuracy.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#website\",\"url\":\"https:\\\/\\\/www.accuracy.com\\\/\",\"name\":\"Accuracy\",\"description\":\"Business Advisers - Financial Consultants\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.accuracy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#organization\",\"name\":\"Accuracy\",\"url\":\"https:\\\/\\\/www.accuracy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.accuracy.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/unnamed-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.accuracy.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/unnamed-3.jpg\",\"width\":512,\"height\":512,\"caption\":\"Accuracy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/accuracy\\\/?originalSubdomain=fr\",\"https:\\\/\\\/www.instagram.com\\\/accuracycareers\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.accuracy.com\\\/#\\\/schema\\\/person\\\/0121122fa331675601ed145cc5dd6182\",\"name\":\"Etienne Levy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c813ed470b69b1f5efb585901ce73ab6e5f4e77dd0533067ad71eab4f54f7b24?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c813ed470b69b1f5efb585901ce73ab6e5f4e77dd0533067ad71eab4f54f7b24?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c813ed470b69b1f5efb585901ce73ab6e5f4e77dd0533067ad71eab4f54f7b24?s=96&d=blank&r=g\",\"caption\":\"Etienne Levy\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy - Accuracy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.accuracy.com\/fr\/retour-sur-la-9e-edition-des-ateliers-sur-le-brevet-organises-par-le-cabinet-davocats-august-debouzy\/","og_locale":"fr_CA","og_type":"article","og_title":"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy","og_description":"Notre associ\u00e9 S\u00e9bastien Gonnet\u00a0a r\u00e9cemment particip\u00e9 \u00e0 la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy, r\u00e9unissant plus de 70 participants. Cet \u00e9v\u00e9nement annuel a rassembl\u00e9 des professionnels de la propri\u00e9t\u00e9 intellectuelle pour \u00e9changer sur les \u00e9volutions majeures et les d\u00e9fis pratiques du secteur des brevets. Le programme de cette [&hellip;]","og_url":"https:\/\/www.accuracy.com\/fr\/retour-sur-la-9e-edition-des-ateliers-sur-le-brevet-organises-par-le-cabinet-davocats-august-debouzy\/","og_site_name":"Accuracy","article_published_time":"2026-07-08T12:22:40+00:00","article_modified_time":"2026-07-08T12:35:49+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.accuracy.com\/wp-content\/uploads\/2023\/10\/Accuracy.png","type":"image\/png"}],"author":"Etienne Levy","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Etienne Levy","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/#article","isPartOf":{"@id":"https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/"},"author":{"name":"Etienne Levy","@id":"https:\/\/www.accuracy.com\/#\/schema\/person\/0121122fa331675601ed145cc5dd6182"},"headline":"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy","datePublished":"2026-07-08T12:22:40+00:00","dateModified":"2026-07-08T12:35:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/"},"wordCount":232,"publisher":{"@id":"https:\/\/www.accuracy.com\/#organization"},"articleSection":["France","News"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/","url":"https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/","name":"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy - Accuracy","isPartOf":{"@id":"https:\/\/www.accuracy.com\/#website"},"datePublished":"2026-07-08T12:22:40+00:00","dateModified":"2026-07-08T12:35:49+00:00","breadcrumb":{"@id":"https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.accuracy.com\/retour-sur-la-9e-edition-des-ateliers-du-brevet-organisee-par-le-cabinet-davocats-august-debouzy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.accuracy.com\/"},{"@type":"ListItem","position":2,"name":"Retour sur la 9e \u00e9dition des Ateliers du Brevet, organis\u00e9e par le cabinet d\u2019avocats August Debouzy"}]},{"@type":"WebSite","@id":"https:\/\/www.accuracy.com\/#website","url":"https:\/\/www.accuracy.com\/","name":"Pr\u00e9cision","description":"Conseillers d'entreprise - Consultants financiers","publisher":{"@id":"https:\/\/www.accuracy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.accuracy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/www.accuracy.com\/#organization","name":"Pr\u00e9cision","url":"https:\/\/www.accuracy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/www.accuracy.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.accuracy.com\/wp-content\/uploads\/2023\/08\/unnamed-3.jpg","contentUrl":"https:\/\/www.accuracy.com\/wp-content\/uploads\/2023\/08\/unnamed-3.jpg","width":512,"height":512,"caption":"Accuracy"},"image":{"@id":"https:\/\/www.accuracy.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/accuracy\/?originalSubdomain=fr","https:\/\/www.instagram.com\/accuracycareers\/"]},{"@type":"Person","@id":"https:\/\/www.accuracy.com\/#\/schema\/person\/0121122fa331675601ed145cc5dd6182","name":"\u00c9tienne L\u00e9vy","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/c813ed470b69b1f5efb585901ce73ab6e5f4e77dd0533067ad71eab4f54f7b24?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c813ed470b69b1f5efb585901ce73ab6e5f4e77dd0533067ad71eab4f54f7b24?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c813ed470b69b1f5efb585901ce73ab6e5f4e77dd0533067ad71eab4f54f7b24?s=96&d=blank&r=g","caption":"Etienne Levy"}}]}},"_links":{"self":[{"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/posts\/66258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/comments?post=66258"}],"version-history":[{"count":16,"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/posts\/66258\/revisions"}],"predecessor-version":[{"id":66281,"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/posts\/66258\/revisions\/66281"}],"wp:attachment":[{"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/media?parent=66258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/categories?post=66258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.accuracy.com\/fr\/wp-json\/wp\/v2\/tags?post=66258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}